{"id":11442,"date":"2025-01-24T09:47:28","date_gmt":"2025-01-24T08:47:28","guid":{"rendered":"https:\/\/brekoverband.de\/about-us\/team\/"},"modified":"2026-03-06T16:37:49","modified_gmt":"2026-03-06T15:37:49","slug":"team","status":"publish","type":"page","link":"https:\/\/brekoverband.de\/en\/about-us\/team\/","title":{"rendered":"Team"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling poli-container-mode-normal\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1372.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_4_5 4_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:80%;--awb-margin-top-large:0px;--awb-spacing-right-large:12%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:12%;--awb-width-medium:83.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:4.608%;--awb-spacing-left-medium:4.608%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top:20px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h1 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:56;line-height:var(--awb-typography1-line-height);\">The BREKO team<\/h1><\/div><div class=\"fusion-text fusion-text-1 fusion-text-no-margin\" style=\"--awb-content-alignment:center;--awb-margin-right:6%;--awb-margin-bottom:60px;--awb-margin-left:6%;\"><p>As the BREKO Association, we are committed to your concerns and your economic success:<\/p>\n<p>At the head office in Bonn, in the capital city office in Berlin, in the European office in Brussels, in the federal states, in the purchasing association and in the service company.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_4_5 4_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:80%;--awb-margin-top-large:0px;--awb-spacing-right-large:12%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:12%;--awb-width-medium:83.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:4.608%;--awb-spacing-left-medium:4.608%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top:20px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.2;\">Bonn head office<\/h2><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-post-cards fusion-post-cards-1 fusion-grid-archive fusion-grid-columns-4\" style=\"--awb-dots-align:center;--awb-active-filter-border-size:3px;--awb-filters-height:36px;--awb-columns-medium:33.3333%;--awb-columns-small:25%;\" data-post-type-label=\"kontakte\"><ul class=\"fusion-grid fusion-grid-4 fusion-flex-align-items-stretch fusion-grid-posts-cards\"><li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1708\" title=\"Henning-Hattendorf-brekoMV25-055\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-scaled.jpg\" class=\"lazyload img-responsive wp-image-15661 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271708%27%20viewBox%3D%270%200%202560%201708%27%3E%3Crect%20width%3D%272560%27%20height%3D%271708%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-200x133.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-400x267.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-600x400.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-800x534.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-1200x800.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Dr. Stephan Albers<\/h5><\/div><div class=\"fusion-text fusion-text-2 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Managing Director<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-3 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1708\" title=\"Henning-Hattendorf-brekoMV25-055\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-scaled.jpg\" class=\"lazyload img-responsive wp-image-15661 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271708%27%20viewBox%3D%270%200%202560%201708%27%3E%3Crect%20width%3D%272560%27%20height%3D%271708%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-200x133.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-400x267.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-600x400.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-800x534.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-1200x800.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekoMV25-055-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Dr. Stephan Albers<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-1\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de.linkedin.com\/in\/stephan-albers-1514bb121\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#097;&#108;b&#101;&#114;&#115;&#064;br&#101;kove&#114;&#098;&#097;n&#100;&#046;&#100;e\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1708\" title=\"Henning-Hattendorf-brekoMV25-056\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-scaled.jpg\" class=\"lazyload img-responsive wp-image-15707 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271708%27%20viewBox%3D%270%200%202560%201708%27%3E%3Crect%20width%3D%272560%27%20height%3D%271708%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-200x133.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-400x267.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-600x400.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-800x534.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-1200x800.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Anna Nass<\/h5><\/div><div class=\"fusion-text fusion-text-4 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Head of Strategy and Finance \/ Managing Director BREKO Servicegesellschaft mbH<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-5 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-3 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1708\" title=\"Henning-Hattendorf-brekoMV25-056\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-scaled.jpg\" class=\"lazyload img-responsive wp-image-15707 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271708%27%20viewBox%3D%270%200%202560%201708%27%3E%3Crect%20width%3D%272560%27%20height%3D%271708%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-200x133.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-400x267.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-600x400.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-800x534.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-1200x800.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/12\/Henning-Hattendorf-brekoMV25-056-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-6 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Anna Nass<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-2\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de.linkedin.com\/in\/anna-nass-b0910167\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#110;ass&#064;br&#101;kov&#101;r&#098;and&#046;de\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-4 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1094\" height=\"692\" title=\"henning-hattendorf-brekofs23-henrik\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik.jpg\" class=\"lazyload img-responsive wp-image-6996 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271094%27%20height%3D%27692%27%20viewBox%3D%270%200%201094%20692%27%3E%3Crect%20width%3D%271094%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik-200x127.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik-400x253.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik-600x380.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik-800x506.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik.jpg 1094w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1094px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-7 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Henrik Harings<\/h5><\/div><div class=\"fusion-text fusion-text-6 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Head of Regulatory Proceedings & Legal Department<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-7 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-5 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-6 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1094\" height=\"692\" title=\"henning-hattendorf-brekofs23-henrik\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik.jpg\" class=\"lazyload img-responsive wp-image-6996 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271094%27%20height%3D%27692%27%20viewBox%3D%270%200%201094%20692%27%3E%3Crect%20width%3D%271094%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik-200x127.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik-400x253.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik-600x380.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik-800x506.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-henrik.jpg 1094w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1094px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-8 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Henrik Harings<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-3\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:har&#105;&#110;&#103;&#115;&#064;&#098;rek&#111;&#118;er&#098;&#097;&#110;&#100;.de\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-6 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-7 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2115\" height=\"1502\" title=\"lisa_1\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1.jpg\" class=\"lazyload img-responsive wp-image-7000 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272115%27%20height%3D%271502%27%20viewBox%3D%270%200%202115%201502%27%3E%3Crect%20width%3D%272115%27%20height%3D%271502%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-200x142.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-400x284.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-600x426.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-800x568.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-1200x852.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1.jpg 2115w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2115px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-9 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Lisa M\u00fcller<\/h5><\/div><div class=\"fusion-text fusion-text-8 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Legal & Regulation Officer<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-9 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-7 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-8 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2115\" height=\"1502\" title=\"lisa_1\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1.jpg\" class=\"lazyload img-responsive wp-image-7000 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272115%27%20height%3D%271502%27%20viewBox%3D%270%200%202115%201502%27%3E%3Crect%20width%3D%272115%27%20height%3D%271502%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-200x142.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-400x284.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-600x426.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-800x568.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1-1200x852.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/lisa_1.jpg 2115w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2115px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-10 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Lisa M\u00fcller<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-4\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/lisa-m%C3%BCller-ab3968230\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#109;u&#101;&#108;l&#101;r&#064;&#098;r&#101;&#107;o&#118;&#101;rb&#097;nd.&#100;&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-8 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-9 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1242\" height=\"692\" title=\"henning-hattendorf-brekofs23-jan2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2.jpg\" class=\"lazyload img-responsive wp-image-6997 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271242%27%20height%3D%27692%27%20viewBox%3D%270%200%201242%20692%27%3E%3Crect%20width%3D%271242%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-200x111.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-400x223.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-600x334.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-800x446.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-1200x669.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2.jpg 1242w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1242px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-11 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Jan Simons<\/h5><\/div><div class=\"fusion-text fusion-text-10 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Head of regional and local politics, member support<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-11 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-9 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-10 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1242\" height=\"692\" title=\"henning-hattendorf-brekofs23-jan2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2.jpg\" class=\"lazyload img-responsive wp-image-6997 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271242%27%20height%3D%27692%27%20viewBox%3D%270%200%201242%20692%27%3E%3Crect%20width%3D%271242%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-200x111.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-400x223.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-600x334.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-800x446.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2-1200x669.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-jan2.jpg 1242w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1242px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-12 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Jan Simons<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-5\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/jan-simons-3b0798208\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:s&#105;m&#111;ns&#064;b&#114;&#101;ko&#118;e&#114;b&#097;&#110;d.de\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-10 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-11 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1123\" height=\"692\" title=\"henning-hattendorf-brekofs23-oli\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli.jpg\" class=\"lazyload img-responsive wp-image-6998 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271123%27%20height%3D%27692%27%20viewBox%3D%270%200%201123%20692%27%3E%3Crect%20width%3D%271123%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli-200x123.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli-400x246.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli-600x370.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli-800x493.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli.jpg 1123w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1123px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-13 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Oliver Ulke<\/h5><\/div><div class=\"fusion-text fusion-text-12 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Deputy Head of National Policy, GAIA-X Project Manager <\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-13 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-11 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-12 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1123\" height=\"692\" title=\"henning-hattendorf-brekofs23-oli\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli.jpg\" class=\"lazyload img-responsive wp-image-6998 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271123%27%20height%3D%27692%27%20viewBox%3D%270%200%201123%20692%27%3E%3Crect%20width%3D%271123%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli-200x123.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli-400x246.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli-600x370.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli-800x493.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-oli.jpg 1123w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1123px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-14 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Oliver Ulke<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-6\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/oliver-ulke\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:u&#108;&#107;&#101;&#064;brek&#111;ve&#114;b&#097;nd&#046;&#100;&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-12 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-13 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1069\" height=\"692\" title=\"henning-hattendorf-brekofs23-roman\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman.jpg\" class=\"lazyload img-responsive wp-image-6999 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271069%27%20height%3D%27692%27%20viewBox%3D%270%200%201069%20692%27%3E%3Crect%20width%3D%271069%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman-200x129.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman-400x259.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman-600x388.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman-800x518.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman.jpg 1069w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1069px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-15 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Roman Skrodzki<\/h5><\/div><div class=\"fusion-text fusion-text-14 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Consultant for local politics<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-15 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-13 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-14 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1069\" height=\"692\" title=\"henning-hattendorf-brekofs23-roman\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman.jpg\" class=\"lazyload img-responsive wp-image-6999 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271069%27%20height%3D%27692%27%20viewBox%3D%270%200%201069%20692%27%3E%3Crect%20width%3D%271069%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman-200x129.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman-400x259.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman-600x388.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman-800x518.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-roman.jpg 1069w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1069px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-16 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Roman Skrodzki<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-7\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/roman-skrodzki-163a751b6\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#115;&#107;ro&#100;z&#107;&#105;&#064;&#098;&#114;e&#107;&#111;ve&#114;&#098;an&#100;.&#100;&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-14 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-15 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1129\" height=\"692\" title=\"henning-hattendorf-brekofs23-alicia1-2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1.jpg\" class=\"lazyload img-responsive wp-image-7001 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271129%27%20height%3D%27692%27%20viewBox%3D%270%200%201129%20692%27%3E%3Crect%20width%3D%271129%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1-200x123.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1-400x245.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1-600x368.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1-800x490.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1.jpg 1129w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1129px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-17 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Alicia H\u00f6fer<\/h5><\/div><div class=\"fusion-text fusion-text-16 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Head of Strategy Projects & Marketing<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-17 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-15 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-16 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1129\" height=\"692\" title=\"henning-hattendorf-brekofs23-alicia1-2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1.jpg\" class=\"lazyload img-responsive wp-image-7001 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271129%27%20height%3D%27692%27%20viewBox%3D%270%200%201129%20692%27%3E%3Crect%20width%3D%271129%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1-200x123.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1-400x245.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1-600x368.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1-800x490.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-alicia1-2-1.jpg 1129w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1129px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-18 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Alicia H\u00f6fer<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-8\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/a-stengel\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:h&#111;&#101;f&#101;r&#064;br&#101;&#107;ov&#101;rb&#097;nd.d&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-16 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-17 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2421\" height=\"1566\" title=\"foto_max_-_kopie\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie.jpg\" class=\"lazyload img-responsive wp-image-7004 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272421%27%20height%3D%271566%27%20viewBox%3D%270%200%202421%201566%27%3E%3Crect%20width%3D%272421%27%20height%3D%271566%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-200x129.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-400x259.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-600x388.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-800x517.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-1200x776.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie.jpg 2421w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2421px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-19 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Maximilian Hanson<\/h5><\/div><div class=\"fusion-text fusion-text-18 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Marketing Manager<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-19 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-17 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-18 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2421\" height=\"1566\" title=\"foto_max_-_kopie\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie.jpg\" class=\"lazyload img-responsive wp-image-7004 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272421%27%20height%3D%271566%27%20viewBox%3D%270%200%202421%201566%27%3E%3Crect%20width%3D%272421%27%20height%3D%271566%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-200x129.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-400x259.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-600x388.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-800x517.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie-1200x776.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_max_-_kopie.jpg 2421w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2421px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-20 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Maximilian Hanson<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-9\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/maximilian-hanson-949679246\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:ha&#110;&#115;o&#110;&#064;&#098;r&#101;&#107;over&#098;&#097;&#110;d.&#100;&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-18 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-19 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1783\" title=\"henning-hattendorf-breko-fotoshooting-laura\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-scaled.jpg\" class=\"lazyload img-responsive wp-image-7005 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271783%27%20viewBox%3D%270%200%202560%201783%27%3E%3Crect%20width%3D%272560%27%20height%3D%271783%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-200x139.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-400x279.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-600x418.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-800x557.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-1200x836.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-21 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Laura Snehotta<\/h5><\/div><div class=\"fusion-text fusion-text-20 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Marketing Manager<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-21 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-19 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-20 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1783\" title=\"henning-hattendorf-breko-fotoshooting-laura\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-scaled.jpg\" class=\"lazyload img-responsive wp-image-7005 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271783%27%20viewBox%3D%270%200%202560%201783%27%3E%3Crect%20width%3D%272560%27%20height%3D%271783%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-200x139.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-400x279.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-600x418.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-800x557.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-1200x836.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-laura-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-22 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Laura Snehotta<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-10\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/laura-snehotta-0731a2116\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:sn&#101;hot&#116;&#097;&#064;b&#114;e&#107;ove&#114;b&#097;&#110;d&#046;d&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-20 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-21 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1759\" title=\"henning-hattendorf-breko-fotoshooting-hagen\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-scaled.jpg\" class=\"lazyload img-responsive wp-image-7007 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271759%27%20viewBox%3D%270%200%202560%201759%27%3E%3Crect%20width%3D%272560%27%20height%3D%271759%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-200x137.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-400x275.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-600x412.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-800x550.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-1200x824.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-23 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Hagen Teimann<\/h5><\/div><div class=\"fusion-text fusion-text-22 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Dual student marketing management<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-23 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-21 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-22 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1759\" title=\"henning-hattendorf-breko-fotoshooting-hagen\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-scaled.jpg\" class=\"lazyload img-responsive wp-image-7007 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271759%27%20viewBox%3D%270%200%202560%201759%27%3E%3Crect%20width%3D%272560%27%20height%3D%271759%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-200x137.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-400x275.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-600x412.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-800x550.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-1200x824.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-hagen-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-24 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Hagen Teimann<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-11\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/hagen-teimann-a55202302\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:t&#101;&#105;man&#110;&#064;b&#114;&#101;&#107;o&#118;&#101;rban&#100;&#046;&#100;e\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-22 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-23 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"754\" height=\"459\" title=\"henning-hattendorf-brekofs23-kerstin1\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1.jpg\" class=\"lazyload img-responsive wp-image-7003 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27754%27%20height%3D%27459%27%20viewBox%3D%270%200%20754%20459%27%3E%3Crect%20width%3D%27754%27%20height%3D%27459%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1-200x122.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1-400x244.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1-600x365.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1.jpg 754w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 754px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-25 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Kerstin Klein<\/h5><\/div><div class=\"fusion-text fusion-text-24 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Project manager<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-25 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-23 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-24 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"754\" height=\"459\" title=\"henning-hattendorf-brekofs23-kerstin1\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1.jpg\" class=\"lazyload img-responsive wp-image-7003 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27754%27%20height%3D%27459%27%20viewBox%3D%270%200%20754%20459%27%3E%3Crect%20width%3D%27754%27%20height%3D%27459%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1-200x122.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1-400x244.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1-600x365.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-kerstin1.jpg 754w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 754px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-26 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Kerstin Klein<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-12\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/kerstin-klein-46b708288\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:k&#108;&#101;i&#110;&#064;&#098;r&#101;k&#111;&#118;&#101;&#114;&#098;a&#110;d.&#100;e\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-24 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-25 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1234\" height=\"720\" title=\"breko_-_9875\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875.jpg\" class=\"lazyload img-responsive wp-image-7011 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271234%27%20height%3D%27720%27%20viewBox%3D%270%200%201234%20720%27%3E%3Crect%20width%3D%271234%27%20height%3D%27720%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-200x117.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-400x233.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-600x350.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-800x467.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-1200x700.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875.jpg 1234w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1234px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-27 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Julia Neubauer-Rieke<\/h5><\/div><div class=\"fusion-text fusion-text-26 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Personnel<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-27 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-25 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-26 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1234\" height=\"720\" title=\"breko_-_9875\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875.jpg\" class=\"lazyload img-responsive wp-image-7011 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271234%27%20height%3D%27720%27%20viewBox%3D%270%200%201234%20720%27%3E%3Crect%20width%3D%271234%27%20height%3D%27720%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-200x117.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-400x233.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-600x350.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-800x467.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875-1200x700.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/breko_-_9875.jpg 1234w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1234px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-28 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Julia Neubauer-Rieke<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-13\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/julia-neubauer-rieke-849338207\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:n&#101;uba&#117;&#101;r&#045;r&#105;&#101;k&#101;&#064;b&#114;&#101;kov&#101;r&#098;&#097;nd.de\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-26 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-27 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1100\" height=\"692\" title=\"henning-hattendorf-brekofs23-ilonka-2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2.jpg\" class=\"lazyload img-responsive wp-image-7008 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271100%27%20height%3D%27692%27%20viewBox%3D%270%200%201100%20692%27%3E%3Crect%20width%3D%271100%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2-200x126.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2-400x252.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2-600x377.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2-800x503.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2.jpg 1100w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1100px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-29 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Ilonka D\u00f6mlang<\/h5><\/div><div class=\"fusion-text fusion-text-28 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Finances<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-29 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-27 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-28 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1100\" height=\"692\" title=\"henning-hattendorf-brekofs23-ilonka-2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2.jpg\" class=\"lazyload img-responsive wp-image-7008 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271100%27%20height%3D%27692%27%20viewBox%3D%270%200%201100%20692%27%3E%3Crect%20width%3D%271100%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2-200x126.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2-400x252.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2-600x377.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2-800x503.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-ilonka-2.jpg 1100w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1100px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-30 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Ilonka D\u00f6mlang<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-14\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/ilonka-d%C3%B6mlang-7ab715292\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:do&#101;&#109;l&#097;ng&#064;&#098;r&#101;&#107;ov&#101;rba&#110;d&#046;d&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-28 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-29 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1800\" title=\"henning-hattendorf-brekofs23-lisa-1\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-scaled.jpg\" class=\"lazyload img-responsive wp-image-7009 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271800%27%20viewBox%3D%270%200%202560%201800%27%3E%3Crect%20width%3D%272560%27%20height%3D%271800%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-200x141.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-400x281.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-600x422.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-800x563.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-1200x844.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-31 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Lisa Scharmentke<\/h5><\/div><div class=\"fusion-text fusion-text-30 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Trainee office management assistant<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-31 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-29 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-30 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1800\" title=\"henning-hattendorf-brekofs23-lisa-1\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-scaled.jpg\" class=\"lazyload img-responsive wp-image-7009 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271800%27%20viewBox%3D%270%200%202560%201800%27%3E%3Crect%20width%3D%272560%27%20height%3D%271800%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-200x141.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-400x281.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-600x422.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-800x563.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-1200x844.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisa-1-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-32 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Lisa Scharmentke<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-15\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/lisa-scharmentke-2913a9283\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:s&#099;&#104;ar&#109;e&#110;t&#107;e&#064;&#098;re&#107;ove&#114;ba&#110;&#100;&#046;&#100;e\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-30 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-31 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1708\" title=\"Henning-Hattendorf-brekoMV25-058\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-scaled.jpg\" class=\"lazyload img-responsive wp-image-15521 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271708%27%20viewBox%3D%270%200%202560%201708%27%3E%3Crect%20width%3D%272560%27%20height%3D%271708%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-200x133.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-400x267.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-600x400.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-800x534.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-1200x800.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-33 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Lukas Hesse<\/h5><\/div><div class=\"fusion-text fusion-text-32 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Werkstudent f\u00fcr Recht & Regulierung<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-33 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-31 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-32 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1708\" title=\"Henning-Hattendorf-brekoMV25-058\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-scaled.jpg\" class=\"lazyload img-responsive wp-image-15521 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271708%27%20viewBox%3D%270%200%202560%201708%27%3E%3Crect%20width%3D%272560%27%20height%3D%271708%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-200x133.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-400x267.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-600x400.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-800x534.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-1200x800.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/11\/Henning-Hattendorf-brekoMV25-058-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-34 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Lukas Hesse<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-16\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:H&#101;ss&#101;&#064;bre&#107;o&#118;er&#098;&#097;nd&#046;d&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-19 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-32 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-33 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"966\" height=\"598\" title=\"processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa.jpeg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa.jpeg\" class=\"lazyload img-responsive wp-image-7010 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27966%27%20height%3D%27598%27%20viewBox%3D%270%200%20966%20598%27%3E%3Crect%20width%3D%27966%27%20height%3D%27598%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa-200x124.jpeg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa-400x248.jpeg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa-600x371.jpeg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa-800x495.jpeg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa.jpeg 966w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 966px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-35 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Corina T\u00f6rkel<\/h5><\/div><div class=\"fusion-text fusion-text-34 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Assistance<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-35 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-33 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-34 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"966\" height=\"598\" title=\"processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa.jpeg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa.jpeg\" class=\"lazyload img-responsive wp-image-7010 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27966%27%20height%3D%27598%27%20viewBox%3D%270%200%20966%20598%27%3E%3Crect%20width%3D%27966%27%20height%3D%27598%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa-200x124.jpeg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa-400x248.jpeg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa-600x371.jpeg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa-800x495.jpeg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/processed-a476ef14-d541-4a5c-8cfc-0a068e20a1fa.jpeg 966w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 966px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-36 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Corina T\u00f6rkel<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-17\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:t&#111;erk&#101;&#108;&#064;bre&#107;over&#098;a&#110;&#100;&#046;de\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling poli-container-mode-normal\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:20px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1372.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-20 fusion_builder_column_4_5 4_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:80%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:12%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:12%;--awb-width-medium:83.3333333333%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:4.608%;--awb-spacing-left-medium:4.608%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-37 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top:20px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.2;\">Capital city office Berlin<\/h2><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-21 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-post-cards fusion-post-cards-2 fusion-grid-archive fusion-grid-columns-4\" style=\"--awb-dots-align:center;--awb-active-filter-border-size:3px;--awb-filters-height:36px;--awb-columns-medium:33.3333%;--awb-columns-small:25%;\" data-post-type-label=\"kontakte\"><ul class=\"fusion-grid fusion-grid-4 fusion-flex-align-items-stretch fusion-grid-posts-cards\"><li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-22 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-34 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-35 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1164\" height=\"692\" title=\"henning-hattendorf-brekofs23-sven\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven.jpg\" class=\"lazyload img-responsive wp-image-7012 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271164%27%20height%3D%27692%27%20viewBox%3D%270%200%201164%20692%27%3E%3Crect%20width%3D%271164%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven-200x119.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven-400x238.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven-600x357.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven-800x476.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven.jpg 1164w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1164px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-38 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Sven Knapp<\/h5><\/div><div class=\"fusion-text fusion-text-36 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Management Capital Office<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-37 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-35 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-36 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1164\" height=\"692\" title=\"henning-hattendorf-brekofs23-sven\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven.jpg\" class=\"lazyload img-responsive wp-image-7012 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271164%27%20height%3D%27692%27%20viewBox%3D%270%200%201164%20692%27%3E%3Crect%20width%3D%271164%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven-200x119.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven-400x238.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven-600x357.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven-800x476.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-sven.jpg 1164w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1164px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-39 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Sven Knapp<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-18\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de.linkedin.com\/in\/sven-knapp-2239a6195\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#107;na&#112;&#112;&#064;b&#114;eko&#118;&#101;&#114;ban&#100;&#046;&#100;e\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-23 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-36 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-37 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1059\" height=\"692\" title=\"henning-hattendorf-brekofs23-lisia2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2.jpg\" class=\"lazyload img-responsive wp-image-7014 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271059%27%20height%3D%27692%27%20viewBox%3D%270%200%201059%20692%27%3E%3Crect%20width%3D%271059%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2-200x131.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2-400x261.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2-600x392.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2-800x523.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2.jpg 1059w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1059px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-40 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Lisia Mix<\/h5><\/div><div class=\"fusion-text fusion-text-38 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Head of Federal and European Policy<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-39 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-37 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-38 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1059\" height=\"692\" title=\"henning-hattendorf-brekofs23-lisia2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2.jpg\" class=\"lazyload img-responsive wp-image-7014 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271059%27%20height%3D%27692%27%20viewBox%3D%270%200%201059%20692%27%3E%3Crect%20width%3D%271059%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2-200x131.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2-400x261.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2-600x392.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2-800x523.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-lisia2.jpg 1059w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1059px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-41 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Lisia Mix<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-19\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/lisia-mix-747716175\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#109;ix&#064;b&#114;ek&#111;ve&#114;b&#097;&#110;&#100;.&#100;e\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-24 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-38 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-39 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1666\" height=\"1131\" title=\"foto_philip_erweitert_2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2.png\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2.png\" class=\"lazyload img-responsive wp-image-7015 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271666%27%20height%3D%271131%27%20viewBox%3D%270%200%201666%201131%27%3E%3Crect%20width%3D%271666%27%20height%3D%271131%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-200x136.png 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-400x272.png 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-600x407.png 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-800x543.png 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-1200x815.png 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2.png 1666w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1666px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-42 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Philip Starke<\/h5><\/div><div class=\"fusion-text fusion-text-40 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Working student federal politics<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-41 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-39 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-40 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1666\" height=\"1131\" title=\"foto_philip_erweitert_2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2.png\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2.png\" class=\"lazyload img-responsive wp-image-7015 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271666%27%20height%3D%271131%27%20viewBox%3D%270%200%201666%201131%27%3E%3Crect%20width%3D%271666%27%20height%3D%271131%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-200x136.png 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-400x272.png 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-600x407.png 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-800x543.png 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2-1200x815.png 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_philip_erweitert_2.png 1666w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1666px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-43 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Philip Starke<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-20\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/philip-starke-307700208\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#083;&#116;a&#114;&#107;e&#064;bre&#107;&#111;&#118;&#101;rb&#097;&#110;d.d&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-25 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-40 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-41 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1141\" height=\"692\" title=\"henning-hattendorf-brekofs23-benedikt\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt.jpg\" class=\"lazyload img-responsive wp-image-7013 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271141%27%20height%3D%27692%27%20viewBox%3D%270%200%201141%20692%27%3E%3Crect%20width%3D%271141%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt-200x121.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt-400x243.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt-600x364.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt-800x485.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt.jpg 1141w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1141px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-44 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Benedikt Kind<\/h5><\/div><div class=\"fusion-text fusion-text-42 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Head of Legal and Regulatory Principles<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-43 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-41 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-42 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1141\" height=\"692\" title=\"henning-hattendorf-brekofs23-benedikt\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt.jpg\" class=\"lazyload img-responsive wp-image-7013 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271141%27%20height%3D%27692%27%20viewBox%3D%270%200%201141%20692%27%3E%3Crect%20width%3D%271141%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt-200x121.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt-400x243.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt-600x364.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt-800x485.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-benedikt.jpg 1141w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1141px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-45 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Benedikt Kind<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-21\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/benedikt-kind-9ba057228\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#107;&#105;nd&#064;br&#101;&#107;ove&#114;b&#097;&#110;d.&#100;e\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-26 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-42 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-43 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1104\" height=\"692\" title=\"henning-hattendorf-brekofs23-matthias2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2.jpg\" class=\"lazyload img-responsive wp-image-7017 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271104%27%20height%3D%27692%27%20viewBox%3D%270%200%201104%20692%27%3E%3Crect%20width%3D%271104%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2-200x125.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2-400x251.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2-600x376.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2-800x501.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2.jpg 1104w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1104px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-46 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Matthias Schuchard<\/h5><\/div><div class=\"fusion-text fusion-text-44 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Head of Press and Public Relations<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-45 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-43 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-44 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"1104\" height=\"692\" title=\"henning-hattendorf-brekofs23-matthias2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2.jpg\" class=\"lazyload img-responsive wp-image-7017 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271104%27%20height%3D%27692%27%20viewBox%3D%270%200%201104%20692%27%3E%3Crect%20width%3D%271104%27%20height%3D%27692%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2-200x125.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2-400x251.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2-600x376.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2-800x501.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-brekofs23-matthias2.jpg 1104w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 1104px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-47 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Matthias Schuchard<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-22\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/matthias-schuchard\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#115;&#099;hu&#099;h&#097;rd&#064;b&#114;&#101;&#107;&#111;&#118;&#101;rband&#046;&#100;e\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-phone awb-icon-phone\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Phone\" data-toggle=\"tooltip\" title=\"Phone\" aria-label=\"phone\" target=\"_self\" rel=\"noopener noreferrer\" href=\"tel:+49 176 300 20 943\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-27 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-44 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-45 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1726\" title=\"henning-hattendorf-breko-fotoshooting-daniel\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-scaled.jpg\" class=\"lazyload img-responsive wp-image-7019 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271726%27%20viewBox%3D%270%200%202560%201726%27%3E%3Crect%20width%3D%272560%27%20height%3D%271726%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-200x135.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-400x270.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-600x405.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-800x539.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-1200x809.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-48 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Daniel Seufert<\/h5><\/div><div class=\"fusion-text fusion-text-46 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Senior Manager Member Support and Development<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-47 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-45 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-46 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1726\" title=\"henning-hattendorf-breko-fotoshooting-daniel\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-scaled.jpg\" class=\"lazyload img-responsive wp-image-7019 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271726%27%20viewBox%3D%270%200%202560%201726%27%3E%3Crect%20width%3D%272560%27%20height%3D%271726%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-200x135.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-400x270.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-600x405.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-800x539.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-1200x809.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/henning-hattendorf-breko-fotoshooting-daniel-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-49 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Daniel Seufert<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-23\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de.linkedin.com\/in\/daniel-seufert-53882a148\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#115;e&#117;fert&#064;b&#114;ek&#111;&#118;&#101;&#114;&#098;an&#100;&#046;d&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-28 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-46 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-47 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"2532\" title=\"Henning-Hattendorf-brekofd25-341\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-scaled.jpg\" class=\"lazyload img-responsive wp-image-13157 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%272532%27%20viewBox%3D%270%200%202560%202532%27%3E%3Crect%20width%3D%272560%27%20height%3D%272532%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-200x198.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-400x396.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-600x593.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-800x791.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-1200x1187.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-50 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Heike Volz<\/h5><\/div><div class=\"fusion-text fusion-text-48 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Assistance Capital Office & Media Cooperations<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-49 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-47 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-48 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"2532\" title=\"Henning-Hattendorf-brekofd25-341\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-scaled.jpg\" class=\"lazyload img-responsive wp-image-13157 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%272532%27%20viewBox%3D%270%200%202560%202532%27%3E%3Crect%20width%3D%272560%27%20height%3D%272532%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-200x198.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-400x396.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-600x593.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-800x791.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-1200x1187.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Henning-Hattendorf-brekofd25-341-1-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-51 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Heike Volz<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-24\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de.linkedin.com\/in\/heike-volz-a8ab1147\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#118;&#111;lz&#064;br&#101;&#107;overb&#097;nd&#046;de\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling poli-container-mode-normal\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:20px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1372.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-29 fusion_builder_column_4_5 4_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:80%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:12%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:12%;--awb-width-medium:83.3333333333%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:4.608%;--awb-spacing-left-medium:4.608%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-52 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top:20px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:40;line-height:1.2;\">BREKO purchasing association<\/h2><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-30 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-post-cards fusion-post-cards-3 fusion-grid-archive fusion-grid-columns-4\" style=\"--awb-dots-align:center;--awb-active-filter-border-size:3px;--awb-filters-height:36px;--awb-columns-medium:33.3333%;--awb-columns-small:25%;\" data-post-type-label=\"kontakte\"><ul class=\"fusion-grid fusion-grid-4 fusion-flex-align-items-stretch fusion-grid-posts-cards\"><li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-31 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-48 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-49 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"485\" height=\"320\" title=\"Foto J\u00fcrgen Magull 2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2.png\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2.png\" class=\"lazyload img-responsive wp-image-16469 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27485%27%20height%3D%27320%27%20viewBox%3D%270%200%20485%20320%27%3E%3Crect%20width%3D%27485%27%20height%3D%27320%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2-200x132.png 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2-400x264.png 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2.png 485w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 485px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-53 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">J\u00fcrgen Magull<\/h5><\/div><div class=\"fusion-text fusion-text-50 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Managing Director<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-51 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-49 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-50 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"485\" height=\"320\" title=\"Foto J\u00fcrgen Magull 2\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2.png\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2.png\" class=\"lazyload img-responsive wp-image-16469 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27485%27%20height%3D%27320%27%20viewBox%3D%270%200%20485%20320%27%3E%3Crect%20width%3D%27485%27%20height%3D%27320%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2-200x132.png 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2-400x264.png 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Juergen-Magull-2.png 485w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 485px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-54 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">J\u00fcrgen Magull<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-25\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de.linkedin.com\/in\/juergenmagull\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:m&#097;g&#117;&#108;l&#064;&#098;&#114;&#101;k&#111;verba&#110;&#100;&#046;&#100;&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-32 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-50 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-51 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"800\" height=\"533\" title=\"Foto Markus Schuster\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster.jpg\" class=\"lazyload img-responsive wp-image-16471 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27800%27%20height%3D%27533%27%20viewBox%3D%270%200%20800%20533%27%3E%3Crect%20width%3D%27800%27%20height%3D%27533%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster-200x133.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster-400x267.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster-600x400.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster.jpg 800w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 800px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-55 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Markus Schuster<\/h5><\/div><div class=\"fusion-text fusion-text-52 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Senior Partner Manager<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-53 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-51 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-52 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"800\" height=\"533\" title=\"Foto Markus Schuster\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster.jpg\" class=\"lazyload img-responsive wp-image-16471 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27800%27%20height%3D%27533%27%20viewBox%3D%270%200%20800%20533%27%3E%3Crect%20width%3D%27800%27%20height%3D%27533%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster-200x133.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster-400x267.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster-600x400.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/Foto-Markus-Schuster.jpg 800w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 800px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-56 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Markus Schuster<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-26\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de.linkedin.com\/in\/markusdennisschuster\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#115;c&#104;&#117;s&#116;e&#114;&#064;&#098;r&#101;&#107;o&#118;e&#114;ban&#100;&#046;&#100;&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-33 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-52 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-53 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1716\" title=\"foto_marcus_koch-1\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-scaled.jpg\" class=\"lazyload img-responsive wp-image-7023 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271716%27%20viewBox%3D%270%200%202560%201716%27%3E%3Crect%20width%3D%272560%27%20height%3D%271716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-200x134.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-400x268.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-600x402.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-800x536.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-1200x804.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-57 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Marcus Koch<\/h5><\/div><div class=\"fusion-text fusion-text-54 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Partner Manager<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-55 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-53 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-54 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2560\" height=\"1716\" title=\"foto_marcus_koch-1\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-scaled.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-scaled.jpg\" class=\"lazyload img-responsive wp-image-7023 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271716%27%20viewBox%3D%270%200%202560%201716%27%3E%3Crect%20width%3D%272560%27%20height%3D%271716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-200x134.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-400x268.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-600x402.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-800x536.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-1200x804.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/01\/foto_marcus_koch-1-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2560px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-58 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Marcus Koch<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-27\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/marcus-koch-berlin\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:k&#111;&#099;h&#064;bre&#107;&#111;v&#101;rb&#097;n&#100;.d&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-34 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-54 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-55 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"566\" height=\"800\" title=\"Arkadius Prosowski BREKO eG\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG.jpg\" class=\"lazyload img-responsive wp-image-14308 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27566%27%20height%3D%27800%27%20viewBox%3D%270%200%20566%20800%27%3E%3Crect%20width%3D%27566%27%20height%3D%27800%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG-200x283.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG-400x565.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG.jpg 566w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 566px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-59 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Arkadius Prosowski<\/h5><\/div><div class=\"fusion-text fusion-text-56 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Manager Prozesse & Strategieprojekte<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-57 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-55 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-56 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"566\" height=\"800\" title=\"Arkadius Prosowski BREKO eG\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG.jpg\" class=\"lazyload img-responsive wp-image-14308 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27566%27%20height%3D%27800%27%20viewBox%3D%270%200%20566%20800%27%3E%3Crect%20width%3D%27566%27%20height%3D%27800%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG-200x283.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG-400x565.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/09\/Arkadius-Prosowski-BREKO-eG.jpg 566w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 566px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-60 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Arkadius Prosowski<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-28\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/arkadius-prosowski-40416b227\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:&#080;r&#111;&#115;&#111;&#119;&#115;ki&#064;&#098;&#114;&#101;kov&#101;&#114;&#098;a&#110;&#100;.&#100;e\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-35 fusion-flex-column team-member-postcard post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-box-shadow:2px 2px 40px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 90%));;--awb-border-radius:10px 10px 10px 10px;--awb-flex-grow:0;--awb-flex-shrink:0;--awb-flex-grow-medium:0;--awb-flex-shrink-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink-small:0;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-56 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-57 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2317\" height=\"1566\" title=\"OD_IMG_0440a_kl\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl.jpg\" class=\"lazyload img-responsive wp-image-7566 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272317%27%20height%3D%271566%27%20viewBox%3D%270%200%202317%201566%27%3E%3Crect%20width%3D%272317%27%20height%3D%271566%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-200x135.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-400x270.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-600x406.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-800x541.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-1200x811.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl.jpg 2317w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2317px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-61 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:35px;--awb-margin-bottom:5px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Olga Bauch<\/h5><\/div><div class=\"fusion-text fusion-text-58 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><p>Team assistance<\/p>\n<\/div><div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;max-width:60px;\"><div class=\"fusion-separator-border sep-single sep-dotted\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color5);border-color:var(--awb-color5);border-top-width:1px;\"><\/div><\/div><div class=\"fusion-text fusion-text-59 details\" style=\"--awb-content-alignment:center;--awb-line-height:1.2;--awb-text-color:var(--awb-color4);\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:30px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-57 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch height100\" style=\"--awb-overflow:hidden;--awb-container-position:absolute;--awb-bg-color:var(--awb-color5);--awb-bg-color-hover:var(--awb-color5);--awb-bg-size:cover;--awb-border-radius:8px 8px 8px 8px;--awb-filter:opacity(0%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:opacity(100%);--awb-filter-parent-hover:opacity(100%);--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-aspect-ratio:1 \/ 1;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-58 hover-type-zoomin has-aspect-ratio\" style=\"border-radius:8px;\"><img decoding=\"async\" width=\"2317\" height=\"1566\" title=\"OD_IMG_0440a_kl\" src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl.jpg\" data-orig-src=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl.jpg\" class=\"lazyload img-responsive wp-image-7566 img-with-aspect-ratio\" data-parent-fit=\"cover\" data-parent-container=\".fusion-image-element\" alt srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272317%27%20height%3D%271566%27%20viewBox%3D%270%200%202317%201566%27%3E%3Crect%20width%3D%272317%27%20height%3D%271566%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-200x135.jpg 200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-400x270.jpg 400w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-600x406.jpg 600w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-800x541.jpg 800w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl-1200x811.jpg 1200w, https:\/\/brekoverband.de\/wp-content\/uploads\/2025\/03\/OD_IMG_0440a_kl.jpg 2317w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 850px) 100vw, 2317px\" \/><\/span><\/div><div class=\"fusion-title title fusion-title-62 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top:35px;--awb-margin-bottom:0px;--awb-margin-top-small:40px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:22;--minFontSize:22;line-height:1.2;\">Olga Bauch<\/h5><\/div><div class=\"fusion-social-links fusion-social-links-29\" style=\"--awb-margin-top:20px;--awb-margin-right:0px;--awb-margin-bottom:40px;--awb-margin-left:0px;--awb-alignment:center;--awb-box-border-top:0px;--awb-box-border-right:0px;--awb-box-border-bottom:0px;--awb-box-border-left:0px;--awb-icon-colors-hover:var(--awb-color5);--awb-box-colors-hover:var(--awb-color1);--awb-box-border-color:var(--awb-color3);--awb-box-border-color-hover:var(--awb-color4);\"><div class=\"fusion-social-networks boxed-icons color-type-custom\"><div class=\"fusion-social-networks-wrapper\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin awb-icon-linkedin\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"LinkedIn\" data-toggle=\"tooltip\" title=\"LinkedIn\" aria-label=\"linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/olga-bauch-3b5722a2\/\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail awb-icon-mail\" style=\"color:var(--awb-color1);font-size:17px;width:17px;background-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-color:hsla(var(--awb-color5-h),var(--awb-color5-s),calc(var(--awb-color5-l) + 10%),var(--awb-color5-a));border-radius:4px;\" data-placement=\"top\" data-title=\"Email\" data-toggle=\"tooltip\" title=\"Email\" aria-label=\"mail\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:ba&#117;&#099;&#104;&#064;&#098;&#114;&#101;ko&#118;er&#098;&#097;&#110;d.&#100;&#101;\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":11425,"menu_order":80,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11442","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/pages\/11442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/comments?post=11442"}],"version-history":[{"count":9,"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/pages\/11442\/revisions"}],"predecessor-version":[{"id":16601,"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/pages\/11442\/revisions\/16601"}],"up":[{"embeddable":true,"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/pages\/11425"}],"wp:attachment":[{"href":"https:\/\/brekoverband.de\/en\/wp-json\/wp\/v2\/media?parent=11442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}